{"id":111,"count":0,"description":"","link":"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/","name":"Logisztika","slug":"logisztika-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logisztika Archives - GLABs - Rakod\u00e1s Management Megold\u00e1sok<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logisztika Archives - GLABs - Rakod\u00e1s Management Megold\u00e1sok\" \/>\n<meta property=\"og:url\" content=\"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/\" \/>\n<meta property=\"og:site_name\" content=\"GLABs - Rakod\u00e1s Management Megold\u00e1sok\" \/>\n<meta property=\"og:image\" content=\"https:\/\/glabs.me\/wp-content\/uploads\/2023\/03\/GLABs-telephelyi-takodas-management-szoftverek.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/tag\\\/logisztika-2\\\/\",\"url\":\"https:\\\/\\\/glabs.me\\\/hu\\\/tag\\\/logisztika-2\\\/\",\"name\":\"Logisztika Archives - GLABs - Rakod\u00e1s Management Megold\u00e1sok\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/tag\\\/logisztika-2\\\/#breadcrumb\"},\"inLanguage\":\"hu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/tag\\\/logisztika-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/glabs.me\\\/hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logisztika\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/#website\",\"url\":\"https:\\\/\\\/glabs.me\\\/hu\\\/\",\"name\":\"GLABs - Rakod\u00e1s Management Megold\u00e1sok\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/glabs.me\\\/hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/#organization\",\"name\":\"GLABs LSS\",\"alternateName\":\"GLABs\",\"url\":\"https:\\\/\\\/glabs.me\\\/hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dev-glabsme.srv1.clbr.hu\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/GLABs.svg\",\"contentUrl\":\"https:\\\/\\\/dev-glabsme.srv1.clbr.hu\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/GLABs.svg\",\"width\":\"68\",\"height\":\"35\",\"caption\":\"GLABs LSS\"},\"image\":{\"@id\":\"https:\\\/\\\/glabs.me\\\/hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GLABs.software\",\"https:\\\/\\\/www.youtube.com\\\/@GLABs\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/glabs\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logisztika Archives - GLABs - Rakod\u00e1s Management Megold\u00e1sok","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/","og_locale":"hu_HU","og_type":"article","og_title":"Logisztika Archives - GLABs - Rakod\u00e1s Management Megold\u00e1sok","og_url":"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/","og_site_name":"GLABs - Rakod\u00e1s Management Megold\u00e1sok","og_image":[{"width":1200,"height":675,"url":"https:\/\/glabs.me\/wp-content\/uploads\/2023\/03\/GLABs-telephelyi-takodas-management-szoftverek.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/","url":"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/","name":"Logisztika Archives - GLABs - Rakod\u00e1s Management Megold\u00e1sok","isPartOf":{"@id":"https:\/\/glabs.me\/hu\/#website"},"breadcrumb":{"@id":"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/#breadcrumb"},"inLanguage":"hu"},{"@type":"BreadcrumbList","@id":"https:\/\/glabs.me\/hu\/tag\/logisztika-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/glabs.me\/hu\/"},{"@type":"ListItem","position":2,"name":"Logisztika"}]},{"@type":"WebSite","@id":"https:\/\/glabs.me\/hu\/#website","url":"https:\/\/glabs.me\/hu\/","name":"GLABs - Rakod\u00e1s Management Megold\u00e1sok","description":"","publisher":{"@id":"https:\/\/glabs.me\/hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/glabs.me\/hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/glabs.me\/hu\/#organization","name":"GLABs LSS","alternateName":"GLABs","url":"https:\/\/glabs.me\/hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/glabs.me\/hu\/#\/schema\/logo\/image\/","url":"https:\/\/dev-glabsme.srv1.clbr.hu\/wp-content\/uploads\/2022\/06\/GLABs.svg","contentUrl":"https:\/\/dev-glabsme.srv1.clbr.hu\/wp-content\/uploads\/2022\/06\/GLABs.svg","width":"68","height":"35","caption":"GLABs LSS"},"image":{"@id":"https:\/\/glabs.me\/hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GLABs.software","https:\/\/www.youtube.com\/@GLABs","https:\/\/www.linkedin.com\/company\/glabs\/"]}]}},"_links":{"self":[{"href":"https:\/\/glabs.me\/hu\/wp-json\/wp\/v2\/tags\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glabs.me\/hu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/glabs.me\/hu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/glabs.me\/hu\/wp-json\/wp\/v2\/posts?tags=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}